{"id":158,"date":"2007-11-30T13:46:00","date_gmt":"2007-11-30T13:46:00","guid":{"rendered":"http:\/\/www.monogatari.info\/?p=158"},"modified":"2007-11-30T13:46:00","modified_gmt":"2007-11-30T13:46:00","slug":"condicionalismos-e-reflexos","status":"publish","type":"post","link":"https:\/\/monogatari.info\/index.php\/2007\/11\/30\/condicionalismos-e-reflexos\/","title":{"rendered":"Condicionalismos e Reflexos"},"content":{"rendered":"<p>Se estivermos com aten\u00e7\u00e3o h\u00e1 coisas muito curiosas a acontecer \u00e0 nossa volta todos os dias. S\u00e3o pequenas coisas, simples; est\u00e3o de tal forma enra\u00edzadas no nosso sub-consciente que normalmente nem sequer damos por elas. H\u00e1 uns dias atr\u00e1s aconteceu-me uma coisa dessas, curiosa.<\/p>\n<p>Estava com um estado de esp\u00edrito muito tranquilo; ultimamente tenho estado muito tranquilo. Tenho tido as minhas rabugices matinais ou quando algo n\u00e3o corre bem, mas de resto desde que comecei a aplicar o m\u00e9todo &#8220;baby steps&#8221; as coisas t\u00eam-me corrido muito melhor, tenho tido muito mais paz. Anyway&#8230; Estava a sair de um centro comercial e ao chegar ao tapete rolante da sa\u00edda apercebi-me que este estava parado. Havia um casal que estava com o carrinho de compras \u00e0 entrada do tapete rolante, com medo de entrar, n\u00e3o fosse o carrinho sair por ali abaixo desembestado. Enquanto decidiam se entravam ou n\u00e3o, estavam a ocupar a entrada do tapete, impedido-me a passagem a toda a gente.<br \/>L\u00e1 consegui entrar no tapete rolante e, como \u00e9 \u00f3bvio, desci-o a caminhar em vez de esperar calmamente que o tapete me levasse ao piso de baixo. Quando cheguei ao fim do tapete sa\u00ed e senti uma desacelera\u00e7\u00e3o n\u00edtida na velocidade a que caminhava; quando na verdade n\u00e3o houve qualquer desacelera\u00e7\u00e3o, pelo menos significativa. Nesse preciso momento apercebi-me que tinha entrado em funcionamento um dos condicionamentos do meu c\u00e9rebro.<br \/>Ser levado por ou caminhar num tapete rolante \u00e9 uma coisa que faz parte do nosso dia-a-dia (do meu pelo menos). De tanto andar nestas coisas, sair de um tapete rolante, compenso de uma forma automatica e inconsciente a velocidade a que vou parado para come\u00e7ar a caminhar num ch\u00e3o que n\u00e3o se mexe debaixo dos meus p\u00e9s.<br \/>Este \u00e9 um processo que j\u00e1 \u00e9 t\u00e3o inconsciente como respirar e como tal quando o tapete rolante est\u00e1 parado n\u00e3o deveria ser necess\u00e1rio compensar a velocidade porque \u00e9 exactamente a mesma coisa que andar num ch\u00e3o normal, no entanto essa compensa\u00e7\u00e3o \u00e9 feita na mesma, tudo por causa do reflexo inconsciente.<br \/>O meu c\u00e9rebro sabia que eu estava a caminhar por cima de um tapete rolante. Sabia tamb\u00e9m que o tapete estava parado, no entanto a primeira informa\u00e7\u00e3o prevaleceu e ent\u00e3o deu ordem ao meu corpo para compensar a velocidade.<\/p>\n<p>Coisas curiosas, n\u00e3o?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se estivermos com aten\u00e7\u00e3o h\u00e1 coisas muito curiosas a acontecer \u00e0 nossa volta todos os dias. S\u00e3o pequenas coisas, simples; est\u00e3o de tal forma enra\u00edzadas no nosso sub-consciente que normalmente nem sequer damos por elas. H\u00e1 uns dias atr\u00e1s aconteceu-me uma coisa dessas, curiosa. Estava com um estado de esp\u00edrito muito tranquilo; ultimamente tenho estado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-158","post","type-post","status-publish","format-standard","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts\/158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/comments?post=158"}],"version-history":[{"count":0,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts\/158\/revisions"}],"wp:attachment":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/media?parent=158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/categories?post=158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/tags?post=158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}