{"id":19,"date":"2011-05-31T14:54:00","date_gmt":"2011-05-31T14:54:00","guid":{"rendered":"http:\/\/www.monogatari.info\/?p=19"},"modified":"2011-05-31T14:54:00","modified_gmt":"2011-05-31T14:54:00","slug":"procura-se-escravo","status":"publish","type":"post","link":"https:\/\/monogatari.info\/index.php\/2011\/05\/31\/procura-se-escravo\/","title":{"rendered":"Procura-se escravo"},"content":{"rendered":"<p>Por acaso n\u00e3o estou \u00e0 procura de trabalho, mas de vez em quando gosto de ver o que h\u00e1 de ofertas e enviar uns CVs para aqui e para ali.<br \/>Hoje deparei-me com uma oferta de emprego (dizem eles) que \u00e9 das coisas mais absurdas que eu j\u00e1 vi; \u00e9 algo assim:<\/p>\n<div style=\"border:1px solid #483413\">Programador de Inform\u00e1tica, m\u00ednimo 12\u00ba Ano de escolaridade, bom conhecimento de Ingl\u00eas, lido, falado e escrito, com experi\u00eancia forte em Microsoft .NET 2.0 (ou superior), C#, Microsoft SQL Server 2005\/2008, TSQL e Ajax com ASP.NET.<br \/>Contrato a termo (6 meses), full-time, 500\u20ac + 6\u20ac de Subs. de Refei\u00e7\u00e3o.<\/div>\n<p>Basicamente pedem um supra-sumo da caganita, que saiba programar em v\u00e1rias l\u00ednguas, que esteja dispon\u00edvel para trabalhar apenas durante seis meses por meia d\u00fazia de tost\u00f5es.<\/p>\n<p>Esta gente droga-se? Andam, se calhar, a snifar tubos de escape?<\/p>\n<p>Bem sei que estamos em crise, bem sei que as coisas n\u00e3o est\u00e3o f\u00e1ceis para as empresas, mas isto \u00e9 literalmente estar a gozar com uma pessoa. Infelizmente, este tipo de ofertas abundam e d\u00e3o resultado porque h\u00e1 sempre quem as aceite (n\u00e3o t\u00eam outra op\u00e7\u00e3o); Sinceramente este tipo de coisas d\u00e1-me a volta ao miolo. N\u00e3o compreendo como \u00e9 que estamos a entrar num sistema de escravatura paga. E n\u00e3o me venham c\u00e1 dizer que a culpa \u00e9 do S\u00f3crates porque este tipo de &#8220;ofertas&#8221; j\u00e1 existia muito antes desse fulano ter ido para o governo. N\u00e3o, a culpa n\u00e3o \u00e9 \u00fanica e exclusivamente do Governo. A culpa, se houver alguma, \u00e9 de todos n\u00f3s.<br \/>\u00c9 de todos n\u00f3s porque fomos n\u00f3s que elegemos o governo actual e todos os outros governos desde 1974 para a frente, porque somos um povo que vive da cultura de tentar entalar o pr\u00f3ximo (consecutivamente), da cultura da m\u00e1-lingua acompanhada de umas minis e uns tremo\u00e7os.<\/p>\n<p>Enfim, nem vale a pena entrar por a\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por acaso n\u00e3o estou \u00e0 procura de trabalho, mas de vez em quando gosto de ver o que h\u00e1 de ofertas e enviar uns CVs para aqui e para ali.Hoje deparei-me com uma oferta de emprego (dizem eles) que \u00e9 das coisas mais absurdas que eu j\u00e1 vi; \u00e9 algo assim: Programador de Inform\u00e1tica, m\u00ednimo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-19","post","type-post","status-publish","format-standard","hentry","category-cronicas-e-historias"],"_links":{"self":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":0,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts\/19\/revisions"}],"wp:attachment":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/media?parent=19"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/categories?post=19"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/tags?post=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}