{"id":206,"date":"2007-02-26T18:16:00","date_gmt":"2007-02-26T18:16:00","guid":{"rendered":"http:\/\/www.monogatari.info\/?p=206"},"modified":"2007-02-26T18:16:00","modified_gmt":"2007-02-26T18:16:00","slug":"o-pardal","status":"publish","type":"post","link":"https:\/\/monogatari.info\/index.php\/2007\/02\/26\/o-pardal\/","title":{"rendered":"O Pardal"},"content":{"rendered":"<p>O Outouno acabou de rebentar, folhas castanhas cobrem o amarelo seco dos campos, alguns farrapos de n\u00favens vagueiam pelo c\u00e9u tapando ocasionalmente o brilho do sol. Uma  brisa suave e h\u00famida brinca com as \u00e1rvores, provocando um som tranquilizante e fazendo voar mais algumas folhas em tons de castanho, amarelo e vermelho.<br \/>\nMisturado com o som do vento, ou\u00e7o os p\u00e1ssaros a chilrear; perto do mo\u00ednho vejo um rebanho de ovelhas e cabras que se v\u00e3o mantendo juntas com os latidos do c\u00e3o pastor. Corro alegremente at\u00e9 ao mo\u00ednho, chutando e levantando as folhas pelo caminho. Quando l\u00e1 chego, sento-me numa rocha grande com os joelhos encostados ao peito enquanto vou atirando pequenos seixos tentando acertar nas \u00e1rvores que est\u00e3o mais longe. Tiro o meu gorro de pele de ovelha e pouso-o no ch\u00e3o ao lado dos meus p\u00e9s. Era um gorro que eu adorava, parecido com o gorro do Davy Crocket.<br \/>\nDe repente chega um pardalito que pousa ao meu lado sem qualquer preocupa\u00e7\u00e3o, como se eu n\u00e3o estivesse ali. Levo a m\u00e3o ao meu bloso do peito das jardineiras de ganga e vou tirando os gr\u00e3os de milho que l\u00e1 tenho dentro de um saco. Guardei-os ali depois de ter ido \u00e0 mercearia compr\u00e1-los para a minha m\u00e3e me fazer pipocas.<br \/>\nDevagarinho pouso a minha m\u00e3o aberta, virada para cima com um punhado de gr\u00e3os. O pardalito afasta-se um pouco, olha para mim meio desconfiado e passo a passo aproxima-se da minha m\u00e3o. Sinto o biquinho dele a tocar-me na palma da m\u00e3o \u00e0 medida que ele apanha os gr\u00e3os e fa\u00e7o um esfor\u00e7o para n\u00e3o retirar a m\u00e3o, aquilo faz c\u00f3cegas.<br \/>\nAo longe ou\u00e7o a minha m\u00e3e a chamar-me para ir jantar, olho para tr\u00e1s e l\u00e1 est\u00e1 ela, na varanda do quarto andar a acenar e a chamar por mim. Levanto-me e vou a correr at\u00e9 casa, sujo de lama com as cal\u00e7as rotas e conto alegremente o que se passou \u00e0 minha m\u00e3e.<br \/>\nNo dia seguinte \u00e0 mesma hora, saio de casa com mais um saco de milho e vou a correr at\u00e9 ao mo\u00ednho na esperan\u00e7a de encontrar novamente o pardal. Sento-me na mesma rocha, tiro um punhado de milho do saco e espero ansiosamente que o pardal volte, mas ele n\u00e3o volta. Est\u00e1 por a\u00ed a voar em liberdade, penso eu. Quando me levanto para voltar para casa reparo em algo que se mexe no meio da relva alta. Ao ver melhor o que \u00e9, vejo o pardal que tinha visto no dia anterior, deitado e quase im\u00f3vel. Numa afli\u00e7\u00e3o terr\u00edvel, pego nele com as minhas m\u00e3os pequenas e levanto-o perto do meu peito. Ainda estava quente. Levei-o para casa o mais depressa que pude sem o abanar muito e mostro-o \u00e0 minha m\u00e3e. Tentamos aliment\u00e1-lo, mas ele n\u00e3o come, damos-lhe \u00e1gua mas tamb\u00e9m n\u00e3o bebe. Arranjei-lhe uma caixa de cart\u00e3o, daquelas onde se embrulham os bolos, forrei-a com algod\u00e3o, num cantinho coloco milho e arroz e deito o pardal no meio do algod\u00e3o. A minha m\u00e3e mandou-me para a cama, mas eu n\u00e3o queria, n\u00e3o conseguia dormir, estava demasiado preocupado com o pardal.Algures a meio da noite acabei eventualmente por adormecer, abra\u00e7ado \u00e0 caixa com o pardal l\u00e1 dentro.<br \/>\nNo dia seguinte acordei e olhei ansiosamente para dentro da caixa, uma parte do milho tinha desaparecido mas o pardal j\u00e1 estava frio, morto. Chorei, chamei a minha m\u00e3e e chorei. A minha m\u00e3e tentou consolar-me o m\u00e1ximo que foi poss\u00edvel, mas eu estava inconsol\u00e1vel.<br \/>\nPeg\u00e1mos na caixa e lev\u00e1mo-la at\u00e9 ao mo\u00ednho, perto da rocha onde tinha encontrado o pardal e a\u00ed eu cavei um buraco e enterrei o pardal. Despedi-me dele e deixei um montinho de milho no s\u00edtio onde o enterrei. Este foi o meu primeiro contacto directo com a morte. Foi uma dor que n\u00e3o consigo descrever e ainda hoje me doi ver qualquer animal a sofrer.<br \/>\nPode ser apenas imagina\u00e7\u00e3o minha, mas alguns dias depois, voltei ao s\u00edtio onde enterrei o pardal e s\u00f3 naquele s\u00edtio, no meio da lama, ao lado da rocha, estavam a rebentar v\u00e1rias novas plantinhas. Verdes e pequeninas. E a\u00ed eu percebi que o pardal continou a viver naquelas plantas.<\/p>\n<p>Esta hist\u00f3ria \u00e9 ver\u00eddica. Est\u00e1 um pouco &#8220;embelezada&#8221; mas aconteceu na minha vida, eu n\u00e3o me lembro qual era a minha idade, mas lembro-me bem das imagens. Chorei a escrever isto, foi a minha despedida ao pardal. Uma despedida que n\u00e3o fiz na altura porque n\u00e3o sabia como.<br \/>\nComecei por escrever um conto imagin\u00e1rio e quando dei por mim estava a reviver a minha inf\u00e2ncia e a escrever sobre ela. \u00c9 muito curioso isto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Outouno acabou de rebentar, folhas castanhas cobrem o amarelo seco dos campos, alguns farrapos de n\u00favens vagueiam pelo c\u00e9u tapando ocasionalmente o brilho do sol. Uma brisa suave e h\u00famida brinca com as \u00e1rvores, provocando um som tranquilizante e fazendo voar mais algumas folhas em tons de castanho, amarelo e vermelho. Misturado com o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,14,20],"tags":[],"class_list":["post-206","post","type-post","status-publish","format-standard","hentry","category-cronicas-e-historias","category-memorias","category-pensamentos-sentimentos"],"_links":{"self":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/comments?post=206"}],"version-history":[{"count":0,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts\/206\/revisions"}],"wp:attachment":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/media?parent=206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/categories?post=206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/tags?post=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}