{"id":2084,"date":"2020-05-20T01:10:25","date_gmt":"2020-05-20T00:10:25","guid":{"rendered":"http:\/\/www.monogatari.info\/dicotomia\/"},"modified":"2020-05-20T01:10:25","modified_gmt":"2020-05-20T00:10:25","slug":"dicotomia","status":"publish","type":"post","link":"https:\/\/monogatari.info\/index.php\/2020\/05\/20\/dicotomia\/","title":{"rendered":"Mais dicotomias"},"content":{"rendered":"\n<p>Foi-me dito que a minha voz \u00e9 um dos meus pontos fortes. Que eu podia\/devia ter seguido o caminho da psicologia ou do ensino.<\/p>\n\n\n\n<p>De facto eu creio que tenho jeito para ensinar e acho que at\u00e9 sou um bom contador de hist\u00f3rias. No entanto, isso implica exposi\u00e7\u00e3o e eu n\u00e3o gosto muito de exposi\u00e7\u00e3o.<\/p>\n\n\n\n<p>\u00c9 uma dicotomia curiosa. E n\u00e3o sei bem como lidar com isto. Para que lado devo &#8220;pender&#8221;.<\/p>\n\n\n\n<p>Sigo a minha intui\u00e7\u00e3o, fa\u00e7o aquilo que me faz mais sentido. Vou saindo da minha zona de conforto sempre que posso e ao mesmo tempo n\u00e3o abuso desse desconforto. Quando me afasto demasiado da zona de conforto come\u00e7o mesmo a sentir-me mal e n\u00e3o h\u00e1 raz\u00e3o nenhuma para isso acontecer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi-me dito que a minha voz \u00e9 um dos meus pontos fortes. Que eu podia\/devia ter seguido o caminho da psicologia ou do ensino. De facto eu creio que tenho jeito para ensinar e acho que at\u00e9 sou um bom contador de hist\u00f3rias. No entanto, isso implica exposi\u00e7\u00e3o e eu n\u00e3o gosto muito de exposi\u00e7\u00e3o. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-2084","post","type-post","status-publish","format-standard","hentry","category-desabafos"],"_links":{"self":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts\/2084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/comments?post=2084"}],"version-history":[{"count":0,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts\/2084\/revisions"}],"wp:attachment":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/media?parent=2084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/categories?post=2084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/tags?post=2084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}