{"id":335,"date":"2005-09-07T13:48:00","date_gmt":"2005-09-07T13:48:00","guid":{"rendered":"http:\/\/www.monogatari.info\/?p=335"},"modified":"2005-09-07T13:48:00","modified_gmt":"2005-09-07T13:48:00","slug":"conversa-de-surdos-parte-ii","status":"publish","type":"post","link":"https:\/\/monogatari.info\/index.php\/2005\/09\/07\/conversa-de-surdos-parte-ii\/","title":{"rendered":"Conversa de surdos &#8211; Parte II"},"content":{"rendered":"\n<p>Dois amigos est\u00e3o numa esplanada a beber um caf\u00e9 e a conversar.<\/p>\n\n\n\n<p>&#8211; Lembras-te do Jo\u00e3o?<br>&#8211; Qual Jorge?!<br>&#8211; N\u00e3o \u00e9 o Jorge, \u00e9 o Jo\u00e3o..! Aquele que tinha uma irm\u00e3 toda grossa!<br>&#8211; Ah&#8230; Est\u00e1s a falar do Joaquim, n\u00e3o \u00e9?!<br>&#8211; N\u00e3o, porra. Estou a falar do Jo\u00e3o Antunes. Aquele que tinha uma irm\u00e3 toda grossa, que esta casada com o Ant\u00f3nio, primo da Marta.!!<br>&#8211; A Marta casou com a irm\u00e3 do Jo\u00e3o?<br>&#8211; Esquece, esquece..!!<br>&#8211; Ok, eu esque\u00e7o. Mas conta l\u00e1, o que \u00e9 que se passa com o Jo\u00e3o?<br>&#8211; Ent\u00e3o, o Jorge teve um acidente de carro e partiu-se todo.<br>&#8211; Ent\u00e3o mas n\u00e3o era o Jo\u00e3o, que tinha uma irm\u00e3 toda grossa que est\u00e1 casada com o Ant\u00f3nio, o primo da Marta?<br>&#8211; N\u00e3o, a Marta \u00e9 que est\u00e1 casada com o Jorge, que por sua vez lhe p\u00f5e um par de palitos com a irm\u00e3 do Jo\u00e3o.<\/p>\n\n\n\n<p>Pronto, eu paro de escrever, eu pr\u00f3prio j\u00e1 me perdi. :o)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dois amigos est\u00e3o numa esplanada a beber um caf\u00e9 e a conversar. &#8211; Lembras-te do Jo\u00e3o?&#8211; Qual Jorge?!&#8211; N\u00e3o \u00e9 o Jorge, \u00e9 o Jo\u00e3o..! Aquele que tinha uma irm\u00e3 toda grossa!&#8211; Ah&#8230; Est\u00e1s a falar do Joaquim, n\u00e3o \u00e9?!&#8211; N\u00e3o, porra. Estou a falar do Jo\u00e3o Antunes. Aquele que tinha uma irm\u00e3 toda grossa, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,17],"tags":[],"class_list":["post-335","post","type-post","status-publish","format-standard","hentry","category-escrita-creativa","category-nonsense"],"_links":{"self":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts\/335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/comments?post=335"}],"version-history":[{"count":0,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/posts\/335\/revisions"}],"wp:attachment":[{"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/media?parent=335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/categories?post=335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monogatari.info\/index.php\/wp-json\/wp\/v2\/tags?post=335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}